{"id":3259,"date":"2019-02-27T03:11:19","date_gmt":"2019-02-27T03:11:19","guid":{"rendered":"http:\/\/kaseybeauty.com\/product\/3259.html"},"modified":"2021-04-29T19:39:01","modified_gmt":"2021-04-29T11:39:01","slug":"makeup-eyeliner-53","status":"publish","type":"product","link":"https:\/\/www.kaseybeauty.com\/pt\/product\/3259.html","title":{"rendered":"Delineador personalizado EL0103"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3259\" class=\"elementor elementor-3259 elementor-bc-flex-widget\" data-elementor-post-type=\"product\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2fcf7593 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2fcf7593\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-38694ff3\" data-id=\"38694ff3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eadd1a7 elementor-widget elementor-widget-text-editor\" data-id=\"eadd1a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #6ec1e4;\"><strong>FABRICA\u00c7\u00c3O DE MAQUIAGEM<\/strong><\/span><\/p><p>A Kasey Beauty fabrica uma ampla variedade de maquiagem para os olhos, desde produtos para l\u00e1bios, produtos para os olhos, produtos para o rosto e qualquer coisa intermedi\u00e1ria. Com instala\u00e7\u00f5es de \u00faltima gera\u00e7\u00e3o, ingredientes de qualidade e mais de 10 anos de experi\u00eancia. Nossos produtos que oferecemos a voc\u00ea garantir\u00e3o que seus produtos sejam consistentes em todos os aspectos e que voc\u00ea possa oferecer a seus clientes mais do que eles desejam. Voc\u00ea pode expandir sua categoria de l\u00e1bio para atender e exceder suas necessidades demogr\u00e1ficas<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0a436c0\" data-id=\"0a436c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cd798d elementor-widget elementor-widget-image\" data-id=\"3cd798d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"490\" height=\"400\" src=\"https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/02\/oem-makeup-manufacture.jpg\" alt=\"Delineador personalizado EL0103\" title=\"Delineador personalizado EL0103\" class=\"attachment-large size-large wp-image-3135\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5dfeea9c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5dfeea9c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64908a58\" data-id=\"64908a58\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63114b69 elementor-widget elementor-widget-image\" data-id=\"63114b69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a target=\"_blank\" href=\"https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/02\/odm-oem-makeup-manufacture-.jpg\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"528\" src=\"https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/02\/odm-oem-makeup-manufacture--1024x528.jpg\" alt=\"Delineador personalizado EL0103\" title=\"Delineador personalizado EL0103\" class=\"attachment-large size-large wp-image-3137\" srcset=\"https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/02\/odm-oem-makeup-manufacture--1024x528.jpg 1024w, https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/02\/odm-oem-makeup-manufacture--750x387.jpg 750w, https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/02\/odm-oem-makeup-manufacture--768x396.jpg 768w, https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/02\/odm-oem-makeup-manufacture-.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8202836 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8202836\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f900f1\" data-id=\"6f900f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8d2b63 elementor-drop-cap-yes elementor-drop-cap-view-default elementor-widget elementor-widget-text-editor\" data-id=\"b8d2b63\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;drop_cap&quot;:&quot;yes&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"line-height: 12px; color: #6ec1e4; text-align: center;\">Costumiza\u00e7\u00e3o\u00a0<\/h2><div><div style=\"text-align: center;\"><span style=\"font-size: 14px;\">delineadores l\u00edquidos \/\u00a0\u00a0<\/span>Delineador em gel ou creme \/ L\u00e1pis Kohl Delineador<\/div><div style=\"text-align: center;\"><span style=\"font-size: 14px;\">Delineador Kajal \/\u00a0<\/span>L\u00e1pis delineador normal \/ Delineador mec\u00e2nico twist-up<\/div><\/div><p><img decoding=\"async\" class=\"alignnone wp-image-3140 size-large\" src=\"https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/02\/OEM-makeup-EYELINER-1024x271.jpg\" alt=\"Delineador personalizado EL0103\" title=\"Delineador personalizado EL0103\" width=\"1024\" height=\"271\" srcset=\"https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/02\/OEM-makeup-EYELINER-1024x271.jpg 1024w, https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/02\/OEM-makeup-EYELINER-750x198.jpg 750w, https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/02\/OEM-makeup-EYELINER-768x203.jpg 768w, https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/02\/OEM-makeup-EYELINER-1536x406.jpg 1536w, https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/02\/OEM-makeup-EYELINER.jpg 1555w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f5dd7bf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f5dd7bf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-084b30e\" data-id=\"084b30e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb5cccf elementor-widget elementor-widget-text-editor\" data-id=\"cb5cccf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 data-elementor-setting-key=\"title\" data-pen-placeholder=\"\u5728\u6b64\u8f93\u5165...\">\u00a0<\/h2><h2 class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" style=\"font-family: Roboto, sans-serif; line-height: 1; color: #6ec1e4; margin-bottom: 0px; font-style: normal; text-align: center;\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"\u5728\u6b64\u8f93\u5165...\">Processo de fabrica\u00e7\u00e3o de maquiagem:<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-df44afc\" data-id=\"df44afc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d0c6eb elementor-widget elementor-widget-text-editor\" data-id=\"6d0c6eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-style: normal; font-weight: 400;\">Cada etapa do processo \u00e9 feita com o maior cuidado, pois o delicado processo de fabrica\u00e7\u00e3o da maquiagem pode desmoronar com um passo em falso. Nossas instala\u00e7\u00f5es s\u00e3o certificadas pela ISO 22716 e tamb\u00e9m cumprem as Boas Pr\u00e1ticas de Fabrica\u00e7\u00e3o (GMP) e Boas Pr\u00e1ticas de Laborat\u00f3rio (GLP), para que voc\u00ea tenha certeza de que seu produto atende aos mais r\u00edgidos padr\u00f5es de qualidade<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31686e8a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"31686e8a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-16f924d9\" data-id=\"16f924d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ef27b5d elementor-widget elementor-widget-text-editor\" data-id=\"2ef27b5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: center; line-height: 12px; color: #6ec1e4;\">Multi-cores est\u00e3o dispon\u00edveis<\/h2><p><a target=\"_blank\" href=\"https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2008\/02\/MAKEUP-COLOR-CHART.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2891\" src=\"https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2008\/02\/MAKEUP-COLOR-CHART.jpg\" alt=\"Delineador personalizado EL0103\" title=\"Delineador personalizado EL0103\" width=\"750\" height=\"242\"><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67008037 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67008037\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65b0719a\" data-id=\"65b0719a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cb26ccc elementor-widget elementor-widget-text-editor\" data-id=\"3cb26ccc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: center; line-height: 12px; color: #6ec1e4;\">embalagem personalizada<\/h2><p style=\"text-align: center;\"><span style=\"background-color: transparent; font-size: 16px; font-style: normal; font-weight: 400;\">\u00a0 \u00a0<\/span><span style=\"background-color: transparent; color: #31424e; font-size: 16px;\">(<\/span><span style=\"background-color: transparent; font-size: 16px; font-style: normal; font-weight: 400;\">C<\/span><span style=\"background-color: transparent; font-size: 16px; font-style: normal; font-weight: 400;\">embalagem da caixa olor,<span style=\"color: #31424e;\">\u00a0<\/span><\/span><span style=\"font-size: 16px; font-style: normal; font-weight: 400; background-color: transparent;\">Embalagem de exibi\u00e7\u00e3o, embalagem de saco opp, a granel<\/span><span style=\"font-style: normal; font-weight: 400; background-color: transparent; font-size: 16px;\">\u00a0embalagem da caixa<\/span><span style=\"font-size: 16px; font-style: normal; font-weight: 400; background-color: transparent;\">\u00a0<\/span><span style=\"font-size: 16px; font-style: normal; font-weight: 400; background-color: transparent;\">)\u00a0<\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2356 size-large\" src=\"https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/02\/OEM-ODM-makeup-packing-1024x292.png\" alt=\"Delineador personalizado EL0103\" title=\"Delineador personalizado EL0103\" width=\"1024\" height=\"292\" srcset=\"https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/02\/OEM-ODM-makeup-packing-1024x292.png 1024w, https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/02\/OEM-ODM-makeup-packing-750x214.png 750w, https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/02\/OEM-ODM-makeup-packing-768x219.png 768w, https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/02\/OEM-ODM-makeup-packing.png 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-85dad57 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"85dad57\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f061a7d\" data-id=\"f061a7d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c765393 elementor-widget elementor-widget-text-editor\" data-id=\"c765393\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table width=\"853\"><tbody><tr><td width=\"160\">Certifica\u00e7\u00e3o:<\/td><td width=\"605\">GMPC, ISO22716, GV, MSDS<\/td><\/tr><tr><td width=\"160\">tempo de amostra<\/td><td width=\"605\">\u00a07-15 dias<\/td><\/tr><tr><td width=\"160\">Tempo de espera<\/td><td width=\"605\">\u00a035-60 dias, dependendo de qual embalagem voc\u00ea escolheu e quantidade<\/td><\/tr><tr><td width=\"160\">Capacidade de produ\u00e7\u00e3o:<\/td><td width=\"605\">30000 pe\u00e7as por dia<\/td><\/tr><tr><td width=\"160\">M\u00e9todos de Pagamento:<\/td><td width=\"605\">TT, L\/C, PayPal, Western Union, Money Gram, Alibaba Trade Assurance<a target=\"_blank\" href=\"https:\/\/www.kaseybeauty.com\/pt\/condicoes-de-pagamento\/\">\u2026\u2026<\/a><\/td><\/tr><tr><td width=\"160\">Termos de pagamento<\/td><td width=\"605\">\u00a0Dep\u00f3sito 30% pago antes da produ\u00e7\u00e3o em massa e saldo 70% pago antes do envio<a target=\"_blank\" href=\"https:\/\/www.kaseybeauty.com\/pt\/condicoes-de-pagamento\/\">\u2026\u2026<\/a><\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-101b3de6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"101b3de6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-675a7db8\" data-id=\"675a7db8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a34dca3 elementor-widget elementor-widget-text-editor\" data-id=\"7a34dca3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong style=\"font-style: inherit;\">Sobre n\u00f3s:\u00a0<\/strong><span style=\"font-style: normal; font-weight: 400; font-size: 16px; font-family: Roboto, sans-serif;\">Yiwu Kasey Cosmetic Co., Ltd \u00e9 uma maquiagem profissional OEM\/ODM China fabricada.\u00a0<\/span><span style=\"font-style: normal; font-weight: 400; font-size: 16px; font-family: Roboto, sans-serif;\">Com mais de 10 anos de experi\u00eancia na ind\u00fastria de cosm\u00e9ticos, nos especializamos na fabrica\u00e7\u00e3o e exporta\u00e7\u00e3o de mercadorias de classe m\u00e9dia a alta.<\/span><\/p><p><span style=\"font-size: 16px;\">Temos o compromisso de fornecer produtos, servi\u00e7os e suporte da mais alta qualidade para nossos clientes que atendam \u00e0s expectativas dos clientes. Alcan\u00e7ar a satisfa\u00e7\u00e3o total do cliente \u00e9 fundamental para o nosso neg\u00f3cio\u00a0<\/span><span style=\"font-size: 16px;\">filosofia.<\/span><\/p><p>Qualidade \u00e9 nossa cultura, trabalhe conosco seu dinheiro em seguran\u00e7a e seus neg\u00f3cios em seguran\u00e7a<a target=\"_blank\" style=\"font-style: inherit; font-weight: inherit; background-color: #ffffff;\" href=\"https:\/\/www.kaseybeauty.com\/pt\/kaseybeauty\/\" data-wplink-edit=\"true\">\u2026mais<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-38dd51d8\" data-id=\"38dd51d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-421dfa64 elementor-widget elementor-widget-image\" data-id=\"421dfa64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a target=\"_blank\" href=\"https:\/\/www.kaseybeauty.com\/pt\/kaseybeauty\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"526\" height=\"303\" src=\"https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/01\/Eyeshadow-makeup-factory.jpg\" alt=\"Delineador personalizado EL0103\" title=\"Delineador personalizado EL0103\" class=\"attachment-large size-large wp-image-470\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a61caef elementor-widget elementor-widget-image\" data-id=\"5a61caef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a target=\"_blank\" href=\"https:\/\/www.kaseybeauty.com\/pt\/kaseybeauty\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"145\" src=\"https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/01\/Makeup-factory-Certificate-1024x145.jpg\" alt=\"Delineador personalizado EL0103\" title=\"Delineador personalizado EL0103\" class=\"attachment-large size-large wp-image-479\" srcset=\"https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/01\/Makeup-factory-Certificate-1024x145.jpg 1024w, https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/01\/Makeup-factory-Certificate-750x106.jpg 750w, https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/01\/Makeup-factory-Certificate-768x109.jpg 768w, https:\/\/www.kaseybeauty.com\/wp-content\/uploads\/2019\/01\/Makeup-factory-Certificate.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a11a073 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a11a073\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ac0398e\" data-id=\"4ac0398e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8089884 elementor-widget elementor-widget-heading\" data-id=\"8089884\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Perguntas frequentes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3857306f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3857306f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-491f938\" data-id=\"491f938\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65d5a9c0 elementor-widget elementor-widget-toggle\" data-id=\"65d5a9c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1701\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1701\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a target=\"_blank\" class=\"elementor-toggle-title\" tabindex=\"0\">P: onde est\u00e1 sua empresa?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1701\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1701\"><p>R: nossa f\u00e1brica na cidade de yiwu, prov\u00edncia de zhejiang, no leste da china.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1702\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1702\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a target=\"_blank\" class=\"elementor-toggle-title\" tabindex=\"0\">P: MOQ<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1702\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1702\"><p>R: Normalmente 12.000 pe\u00e7as, mas podemos fazer algumas cores para voc\u00ea, cada cor MOQ 2000-3000\u00a0<span style=\"color: #666666; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-style: normal; font-weight: 400;\">Pe\u00e7as<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1703\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1703\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a target=\"_blank\" class=\"elementor-toggle-title\" tabindex=\"0\">P: como encomendar?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1703\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1703\"><p>R: Por favor, visite esta p\u00e1gina<a target=\"_blank\" href=\"https:\/\/www.kaseybeauty.com\/pt\/how-to-place-order\/\"><b><u> Como fazer o pedido<\/u><\/b><\/a>\u00a0 ou envie-nos um requisito via <b>E-mail: <\/b>Mark@kaseybeauty.com, <b>Skype:<\/b> mark_hy , <b>Bate-papo: <\/b>122254335 e <b>telefone\/whatsapp<\/b>:+8613282915312<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1704\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1704\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a target=\"_blank\" class=\"elementor-toggle-title\" tabindex=\"0\">P: podemos obter a amostra para verificar antes de colocar grande quantidade?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1704\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1704\"><p>R: sim, fa\u00e7a amostras em torno de 5-12 dias ap\u00f3s o custo da amostra recebida, e isso pode ser reembolsado ap\u00f3s o pedido.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1705\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1705\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a target=\"_blank\" class=\"elementor-toggle-title\" tabindex=\"0\"> P: Quanto tempo leva para fabricar uma vez que um pedido \u00e9 feito? <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1705\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1705\"><p>R: 35-60 dias ap\u00f3s o pagamento recebido e confirma\u00e7\u00e3o da arte, enquanto isso depende da quantidade.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1706\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1706\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a target=\"_blank\" class=\"elementor-toggle-title\" tabindex=\"0\">P: Voc\u00ea testa seus produtos em animais?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1706\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1706\"><p>R: Nossos produtos s\u00e3o 100% livres de crueldade, nenhum dos quais \u00e9 testado em animais, apenas funcion\u00e1rios.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1707\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1707\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a target=\"_blank\" class=\"elementor-toggle-title\" tabindex=\"0\">P: Quais s\u00e3o as melhores maneiras de enviar minhas coisas <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1707\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1707\"><p>R: 1. Se a quantidade for pequena, nosso conselho via a\u00e9rea, como UPS, FEDEX, DHL etc.<br \/>\u00a0 \u00a0 2. Se a quantidade for maior, nosso conselho \u00e9 enviado por mar<a target=\"_blank\" href=\"https:\/\/www.kaseybeauty.com\/pt\/delivery\/\"><u>\u2026mais<\/u><\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1708\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1708\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a target=\"_blank\" class=\"elementor-toggle-title\" tabindex=\"0\">Q: Ordem ou amostras n\u00e3o recebidas?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1708\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1708\"><p>R: Forneceremos um n\u00famero de rastreamento e voc\u00ea poder\u00e1 rastrear seu pedido em todas as etapas, mas se encontrar algum problema, entre em contato conosco aqui.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1709\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-1709\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a target=\"_blank\" class=\"elementor-toggle-title\" tabindex=\"0\">P: O que devo fazer se algum item estiver quebrado? <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1709\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-1709\"><p>R: Se um produto estiver danificado ap\u00f3s o recebimento, podemos reembols\u00e1-lo por esse(s) item(ns) se voc\u00ea entrar em contato com o suporte t\u00e9cnico. Observe que voc\u00ea pode ser solicitado a fornecer fotos.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-17010\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-17010\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a target=\"_blank\" class=\"elementor-toggle-title\" tabindex=\"0\">P: Os produtos est\u00e3o em conformidade com os regulamentos de cosm\u00e9ticos, como FDA e UE?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-17010\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-17010\"><p>R: sim, nossa f\u00e1brica tem<a target=\"_blank\" href=\"https:\/\/www.kaseybeauty.com\/pt\/certificate\/\"> <u>ISO22716\/GMPC<\/u><\/a> certificado e a maioria dos nossos ingredientes s\u00e3o importados de fornecedores mundialmente famosos como Sun Chemical, Kingfisher, Kahl, Croda, Merch, Engelhard, etc. depois de fazer o pedido, ofereceremos MSDS (Material Safety Data Sheets) para voc\u00ea<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-797e64a0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"797e64a0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3dfbd08d\" data-id=\"3dfbd08d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52b4f619 elementor-widget elementor-widget-text-editor\" data-id=\"52b4f619\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>MELHOR SERVI\u00c7O E ACONSELHAMENTO AMIG\u00c1VEL\u00a0<\/strong> \u00a0Se voc\u00ea precisar de alguma informa\u00e7\u00e3o extra sobre qualquer um de nossos produtos de beleza, entre em contato conosco por e-mail ou Whatsapp etc.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"A Kasey Beauty fabrica uma ampla variedade de produtos para os l\u00e1bios, desde batom, brilho labial e protetor labial e qualquer coisa intermedi\u00e1ria. Com instala\u00e7\u00f5es de \u00faltima gera\u00e7\u00e3o, ingredientes de qualidade e mais de 10 anos de experi\u00eancia.","protected":false},"featured_media":3238,"menu_order":748,"template":"","meta":[],"class_list":["post-3259","product","type-product","status-publish","has-post-thumbnail","hentry","products-eyeliner"],"_links":{"self":[{"href":"https:\/\/www.kaseybeauty.com\/pt\/wp-json\/wp\/v2\/product\/3259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaseybeauty.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kaseybeauty.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/www.kaseybeauty.com\/pt\/wp-json\/wp\/v2\/product\/3259\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaseybeauty.com\/pt\/wp-json\/wp\/v2\/media\/3238"}],"wp:attachment":[{"href":"https:\/\/www.kaseybeauty.com\/pt\/wp-json\/wp\/v2\/media?parent=3259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}